{"id":14488,"date":"2025-07-05T15:09:39","date_gmt":"2025-07-05T13:09:39","guid":{"rendered":"https:\/\/mediadorconflictos.com\/?p=14488"},"modified":"2025-09-29T16:16:03","modified_gmt":"2025-09-29T14:16:03","slug":"mediacio-hipotecaria-a-catalunya-i-espanya-una-via-legal-humana-i-eficac-per-resoldre-conflictes","status":"publish","type":"post","link":"https:\/\/mediadorconflictos.com\/ca\/mediacio-hipotecaria-a-catalunya-i-espanya-una-via-legal-humana-i-eficac-per-resoldre-conflictes\/","title":{"rendered":"Mediaci\u00f3 hipotec\u00e0ria a Catalunya i Espanya: una via legal, humana i efica\u00e7 per resoldre conflictes"},"content":{"rendered":"<h3><strong>\ud83c\udfe0<\/strong><strong> Mediaci\u00f3 hipotec\u00e0ria a Catalunya i Espanya: una via legal, humana i efica\u00e7 per resoldre conflictes<\/strong><\/h3>\n<p>La mediaci\u00f3 hipotec\u00e0ria \u00e9s una eina cada cop m\u00e9s rellevant en l\u2019\u00e0mbit de la resoluci\u00f3 alternativa de conflictes. Tot i que encara \u00e9s poc coneguda entre la ciutadania, pot resultar <strong>decisiva per evitar la judicialitzaci\u00f3 de situacions cr\u00edtiques<\/strong> relacionades amb l\u2019habitatge, especialment quan hi ha risc de perdre\u2019l per impagaments o dificultats econ\u00f2miques.<\/p>\n<p>En aquest article t\u2019expliquem <strong>qu\u00e8 \u00e9s la mediaci\u00f3 hipotec\u00e0ria<\/strong>, <strong>com funciona<\/strong>, <strong>quins serveis hi ha disponibles a Catalunya i Espanya<\/strong>, i <strong>quines opcions tens si necessites ajuda<\/strong>, ja sigui des de la via p\u00fablica o privada.<\/p>\n<p><strong>Qu\u00e8 \u00e9s la mediaci\u00f3 hipotec\u00e0ria?<\/strong><\/p>\n<p>Es tracta d\u2019un <strong>proc\u00e9s voluntari i confidencial<\/strong>, guiat per un <strong>mediador o mediadora professional<\/strong>, que facilita la comunicaci\u00f3 i negociaci\u00f3 entre una persona deutora i una entitat financera (normalment un banc o caixa) per abordar un <strong>conflicte relacionat amb el pagament de la hipoteca<\/strong>, habitualment en situaci\u00f3 de dificultat greu o impagament.<\/p>\n<p>El proc\u00e9s t\u00e9 com a objectiu <strong>trobar solucions pactades<\/strong>, justes i viables, com poden ser:<\/p>\n<ul>\n<li>Refinan\u00e7ament o reestructuraci\u00f3 del deute.<\/li>\n<li>Quitan\u00e7a (condonaci\u00f3 parcial del deute).<\/li>\n<li>Ajornaments o car\u00e8ncies de pagament.<\/li>\n<li>Daci\u00f3 en pagament amb opci\u00f3 de lloguer social posterior.<\/li>\n<li>Pactes que evitin processos d\u2019execuci\u00f3 hipotec\u00e0ria o desnonament.<\/li>\n<\/ul>\n<p><strong>La mediaci\u00f3 hipotec\u00e0ria a Catalunya<\/strong><\/p>\n<p>Catalunya compta amb una eina fonamental en aquest \u00e0mbit: <strong>OFIDEUTE<\/strong>, el <strong>Servei d\u2019Intermediaci\u00f3 en Deutes de l\u2019Habitatge<\/strong> impulsat per la Generalitat a trav\u00e9s de l\u2019Ag\u00e8ncia de l\u2019Habitatge.<\/p>\n<p><strong>\ud83d\udd39<\/strong><strong> Qu\u00e8 ofereix Ofideute?<\/strong><\/p>\n<ul>\n<li>Assessorament gratu\u00eft i personalitzat.<\/li>\n<li>Intermediaci\u00f3 directa amb l\u2019entitat financera.<\/li>\n<li>Suport jur\u00eddic i econ\u00f2mic a la persona o fam\u00edlia afectada.<\/li>\n<li>Possibilitat de canalitzar el cas cap a la mediaci\u00f3 o l\u2019acord extrajudicial.<\/li>\n<\/ul>\n<p>Ofideute est\u00e0 pensat especialment per a <strong>persones en risc de vulnerabilitat<\/strong> que poden perdre el seu habitatge habitual. Opera en coordinaci\u00f3 amb serveis socials municipals, diputacions i col\u00b7legis professionals (com el de l\u2019Advocacia o d\u2019Economistes).<\/p>\n<p><strong>La mediaci\u00f3 hipotec\u00e0ria a nivell estatal<\/strong><\/p>\n<p>Tot i que no hi ha un servei \u00fanic i centralitzat com Ofideute, l\u2019Estat espanyol ha promogut iniciatives importants, com ara:<\/p>\n<ul>\n<li>El <strong>Codi de Bones Pr\u00e0ctiques banc\u00e0ries<\/strong> (RDL 6\/2012), que estableix mesures de protecci\u00f3 per a deutors hipotecaris vulnerables.<\/li>\n<li>Programes auton\u00f2mics i locals d\u2019intermediaci\u00f3 hipotec\u00e0ria en comunitats com Madrid, Andalusia o la Comunitat Valenciana.<\/li>\n<li>La possibilitat de rec\u00f3rrer a la <strong>mediaci\u00f3 civil i mercantil<\/strong> regulada per la <strong>Llei 5\/2012<\/strong>, en aquells casos on hi ha voluntat de les parts de negociar fora dels tribunals.<\/li>\n<\/ul>\n<p><strong>\ud83e\udd1d<\/strong><strong> Es pot fer mediaci\u00f3 hipotec\u00e0ria privada?<\/strong><\/p>\n<p><strong>S\u00ed.<\/strong> La mediaci\u00f3 privada \u00e9s una opci\u00f3 plenament legal i v\u00e0lida per afrontar conflictes amb entitats financeres, i pot ser especialment \u00fatil quan:<\/p>\n<ul>\n<li>Hi ha voluntat de di\u00e0leg per part del banc.<\/li>\n<li>Es busca una soluci\u00f3 m\u00e9s r\u00e0pida i personalitzada.<\/li>\n<li>El cas no encaixa en els criteris de serveis p\u00fablics com Ofideute.<\/li>\n<li>Es vol evitar la judicialitzaci\u00f3 del conflicte.<\/li>\n<\/ul>\n<p>A \ud83c\udf10 <a href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fmediadorconflictos.com%2F&amp;data=05%7C02%7C%7Ca0b40254c08349f6e00e08ddbaee9f4e%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C638872256256480194%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=4rVGFKS9BqX54Qpy2rlT00Sl0IivsxWCgwklKxz5%2BJA%3D&amp;reserved=0\">https:\/\/mediadorconflictos.com<\/a> , com a equip professional en gesti\u00f3 de conflictes, oferim <strong>mediaci\u00f3 hipotec\u00e0ria privada amb una mirada humana, imparcial i adaptada a cada situaci\u00f3<\/strong>. El nostre objectiu \u00e9s <strong>restablir la comunicaci\u00f3, analitzar opcions i facilitar acords possibles<\/strong>, tenint cura de les persones i del seu entorn.<\/p>\n<p><strong>Beneficis de la mediaci\u00f3 hipotec\u00e0ria<\/strong><\/p>\n<ul>\n<li>Evita litigis llargs, costosos i emocionalment durs.<\/li>\n<li>Permet <strong>protegir l\u2019habitatge habitual<\/strong> i la dignitat de les fam\u00edlies.<\/li>\n<li>Genera solucions realistes i acordades per ambdues parts.<\/li>\n<li>Redueix l\u2019estr\u00e8s i l\u2019impacte psicosocial de la situaci\u00f3.<\/li>\n<li>S\u2019alinea amb la nova <strong>Llei Org\u00e0nica 1\/2025<\/strong>, que aposta pels <strong>MASC<\/strong> (Mitjans Adequats de Soluci\u00f3 de Conflictes) com a via preferent abans d\u2019accedir als jutjats.<\/li>\n<\/ul>\n<p><strong>\ud83d\udcec<\/strong><strong> Necessites orientaci\u00f3 o assessorament?<\/strong><\/p>\n<p>Si et trobes en una situaci\u00f3 de conflicte amb la teva entitat financera, o tens risc de p\u00e8rdua del teu habitatge per impagaments, <strong>posa\u2019t en contacte amb nosaltres<\/strong>. T\u2019informarem amb claredat i sense comprom\u00eds sobre les opcions p\u00fabliques i privades disponibles.<\/p>\n<p>\ud83d\udce9 <a href=\"mailto:daniel@mediadorconflictos.com\"><strong>daniel@mediadorconflictos.com<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udfe0 Mediaci\u00f3 hipotec\u00e0ria a Catalunya i Espanya: una via legal, humana i efica\u00e7 per resoldre conflictes La mediaci\u00f3 hipotec\u00e0ria \u00e9s una eina cada cop m\u00e9s rellevant en l\u2019\u00e0mbit de la resoluci\u00f3 alternativa de conflictes. Tot i que encara \u00e9s poc coneguda entre la ciutadania, pot&#8230;<\/p>\n","protected":false},"author":3,"featured_media":14483,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-14488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mediacio-i-conciliacio"],"_links":{"self":[{"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/posts\/14488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/comments?post=14488"}],"version-history":[{"count":3,"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/posts\/14488\/revisions"}],"predecessor-version":[{"id":15749,"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/posts\/14488\/revisions\/15749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/media\/14483"}],"wp:attachment":[{"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/media?parent=14488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/categories?post=14488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mediadorconflictos.com\/ca\/wp-json\/wp\/v2\/tags?post=14488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}